{"id":4229,"date":"2026-01-23T14:34:14","date_gmt":"2026-01-23T12:34:14","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/?p=4229"},"modified":"2026-01-23T14:34:14","modified_gmt":"2026-01-23T12:34:14","slug":"acquisto-della-cittadinanza-per-beneficio-di-legge-recenti-modifiche-art-4-comma-1-bis-lettera-b-della-legge-5-febbraio-1992-n-91","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2026\/01\/acquisto-della-cittadinanza-per-beneficio-di-legge-recenti-modifiche-art-4-comma-1-bis-lettera-b-della-legge-5-febbraio-1992-n-91\/","title":{"rendered":"Acquisto della Cittadinanza per \u201dbeneficio di legge\u201d: recenti modifiche art. 4 comma 1-bis, lettera b della Legge 5 febbraio 1992, n. 91"},"content":{"rendered":"<p>Si avvisa la gentile utenza che la legge di bilancio 2026 (Legge 30 dicembre 2025, n. 199) ha apportato alcune modifiche alle norme che regolano la registrazione degli atti di nascita dei minori\u00a0nati dopo il 24 maggio 2025\u00a0(art. 4 comma 1 bis, lettera b della Legge 5 febbraio 1992, n.91). Nello specifico:<\/p>\n<p>le dichiarazioni rese dai genitori \u2013 di cui almeno uno cittadino per nascita \u2013 ai sensi dell\u2019articolo 4, comma 1-bis, lettera b) della Legge n. 91\/1992, dal <strong>1 gennaio 2026 possono essere presentate entro tre anni<\/strong> (e non pi\u00f9 entro un anno) dalla nascita del minore o dalla data successiva in cui \u00e8 stabilita la filiazione, anche adottiva, da cittadino italiano. La normativa ha quindi esteso di due anni il termine entro cui la dichiarazione pu\u00f2 essere presentata.<br \/>\nInoltre, per tutte le richieste di trascrizione per \u201cbeneficio di legge\u201d\u00a0pervenute dal 1 gennaio 2026\u00a0(sia per i nati dal 24 maggio 2025 che per i figli minori alla data di entrata in vigore del Decreto Legge)\u00a0<strong>non sar\u00e0 pi\u00f9 richiesto\u00a0il pagamento del contributo di \u20ac250<\/strong> previsto dall\u2019articolo 9-bis della Legge n. 91\/1992. L\u2019istanza e la sua trattazione saranno quindi gratuite. Per tutte le istanze, invece, gi\u00e0 ricevute e\/o avviate entro il 31 dicembre 2025, si applicher\u00e0 il contributo di \u20ac 250.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Si avvisa la gentile utenza che la legge di bilancio 2026 (Legge 30 dicembre 2025, n. 199) ha apportato alcune modifiche alle norme che regolano la registrazione degli atti di nascita dei minori\u00a0nati dopo il 24 maggio 2025\u00a0(art. 4 comma 1 bis, lettera b della Legge 5 febbraio 1992, n.91). Nello specifico: le dichiarazioni rese [&hellip;]","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-4229","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/4229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=4229"}],"version-history":[{"count":1,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/4229\/revisions"}],"predecessor-version":[{"id":4231,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/4229\/revisions\/4231"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=4229"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=4229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}