{"id":3090,"date":"2024-06-10T09:04:58","date_gmt":"2024-06-10T06:04:58","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/?p=3090"},"modified":"2024-07-25T09:24:09","modified_gmt":"2024-07-25T06:24:09","slug":"programma-eta-il-importanti-informazioni-per-viaggi-in-israele-in-esenzione-da-visto","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2024\/06\/programma-eta-il-importanti-informazioni-per-viaggi-in-israele-in-esenzione-da-visto\/","title":{"rendered":"Programma ETA-IL. Importanti informazioni per viaggi in Israele in esenzione da visto"},"content":{"rendered":"<p>Dal 1\u00b0 luglio 2024 i cittadini italiani che intendono recarsi in Israele per turismo o motivi di lavoro in esenzione da visto (soggiorno breve fino a 90 giorni) dovranno dotarsi di un\u2019autorizzazione preventiva al viaggio prima di potersi imbarcare su un volo o di recarsi alla frontiera. Il nuovo sistema ETA-IL prevede la necessit\u00e0 di trasmettere la propria istanza di ingresso per il tramite del sito <a href=\"https:\/\/israel-entry.piba.gov.il\/\">https:\/\/israel-entry.piba.gov.il\/<\/a>. Il servizio ha un costo di 25 ILS (al cambio attuale circa 6,5 Euro) e, in caso di approvazione, permette di ottenere un\u2019autorizzazione al viaggio valida 2 anni o, se richiesta con passaporto di validit\u00e0 residua inferiore ai due anni, fino alla data di scadenza del documento di viaggio. L\u2019autorizzazione deve essere rinnovata nel caso di cambio di passaporto, generalit\u00e0, cambio di sesso o cittadinanza.<\/p>\n<p>Per i cittadini di sola nazionalit\u00e0 italiana il programma sar\u00e0 utilizzato in fase sperimentale, senza alcun costo, a partire dal 1\u00b0 luglio p.v. mentre entrer\u00e0 <strong>a regime dal 1\u00b0 agosto 2024<\/strong>. Le autorit\u00e0 locali invitano all\u2019utilizzo della piattaforma anche durante il periodo sperimentale.<\/p>\n<p>Ricordiamo che ETA-IL non fornisce tuttavia garanzia di ammissione in territorio israeliano, rimettendo ogni valutazione e decisione alle competenti Autorit\u00e0 di frontiera. ETA-IL non dovr\u00e0 essere utilizzato dai doppi cittadini in possesso della cittadinanza israeliana che entreranno in Israele con passaporto israeliano o che entreranno su passaporto italiano se lo stesso passaporto italiano \u00e8 collegato al loro numero identificativo israeliano o se all\u2019ingresso, oltre al passaporto italiano, esibiranno anche quello israeliano. Per ulteriori informazioni e restrizioni, invitiamo a consultare il sito internet della <a href=\"https:\/\/israel-entry.piba.gov.il\/\"><em>Popolutation and Immigration Authority<\/em><\/a> o a contattare il servizio di assistenza all\u2019indirizzo di posta elettronica <a href=\"mailto:eta@piba.gov.il\">eta@piba.gov.il<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Dal 1\u00b0 luglio 2024 i cittadini italiani che intendono recarsi in Israele per turismo o motivi di lavoro in esenzione da visto (soggiorno breve fino a 90 giorni) dovranno dotarsi di un\u2019autorizzazione preventiva al viaggio prima di potersi imbarcare su un volo o di recarsi alla frontiera. Il nuovo sistema ETA-IL prevede la necessit\u00e0 di [&hellip;]","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-3090","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=3090"}],"version-history":[{"count":1,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3090\/revisions"}],"predecessor-version":[{"id":3093,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3090\/revisions\/3093"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=3090"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=3090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}