{"id":1888,"date":"2017-05-15T08:31:17","date_gmt":"2017-05-15T05:31:17","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2017\/05\/ripristino-temporaneo-dei-controlli\/"},"modified":"2017-05-15T08:31:17","modified_gmt":"2017-05-15T05:31:17","slug":"ripristino-temporaneo-dei-controlli","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2017\/05\/ripristino-temporaneo-dei-controlli\/","title":{"rendered":"Ripristino temporaneo dei controlli alle frontiere interne in occasione del Vertice G7 di Taormina"},"content":{"rendered":"<p>Si comunica che, in occasione del Vertice G7, in programma a Taormina il 26 e 27 maggio, per il periodo dal 10 al 30 maggio sono stati riattivati i controlli alle frontiere interne terrestri, aree e marittime.<\/p>\n<p>Quanto alle modalit\u00e0 operative di tale misura, si precisa che ai viaggiatori stranieri provenienti dall&#8217;area Schengen non verr\u00e0 applicata la disposizione, prevista dal Codice Frontiere Schengen, dell&#8217;apposizione del timbro di ingresso sul passaporto. Di conseguenza, gli stranieri provenienti da un altro Stato Schengen, in possesso di un VSU valido per un solo ingresso (con timbro di ingresso gi\u00e0 apposto all&#8217;atto dell&#8217;ingresso nello Spazio Schengen), verranno considerati in possesso di un valido titolo che li autorizzi all&#8217;ingresso in territorio italiano, purch\u00e9&#8217; il visto sia ancora in corso di validit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"Si comunica che, in occasione del Vertice G7, in programma a Taormina il 26 e 27 maggio, per il periodo dal 10 al 30 maggio sono stati riattivati i controlli alle frontiere interne terrestri, aree e marittime. Quanto alle modalit\u00e0 operative di tale misura, si precisa che ai viaggiatori stranieri provenienti dall&#8217;area Schengen non verr\u00e0 [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1888","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1888"}],"version-history":[{"count":0,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1888\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1888"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}