{"id":1381,"date":"2020-01-31T10:16:40","date_gmt":"2020-01-31T08:16:40","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2020\/01\/referendum-costituzionale-del-29\/"},"modified":"2020-01-31T10:16:40","modified_gmt":"2020-01-31T08:16:40","slug":"referendum-costituzionale-del-29","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2020\/01\/referendum-costituzionale-del-29\/","title":{"rendered":"REFERENDUM COSTITUZIONALE DEL 29 MARZO 2020"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>VOTO PER CORRISPONDENZA DEI CITTADINI ITALIANI RESIDENTI ALL\u2019ESTERO <\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>E <\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>OPZIONE DI VOTO IN ITALIA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">L\u2019Ufficio centrale per il referendum della Corte di Cassazione, con ordinanza depositata in data 23 gennaio 2020, ha dichiarato che la richiesta di referendum sul testo di legge costituzionale recante \u201cmodifica degli articoli 56, 57 e 59 della Costituzione in materia di riduzione del numero dei parlamentari\u201d, \u00e8 conforme all\u2019art. 138 Cost. ed ha accertato la legittimit\u00e0 del quesito referendario dalla stessa proposto.<\/p>\n<p style=\"text-align: justify;\">Con Decreto del Presidente della Repubblica del 28 gennaio 2020, pubblicato nella Gazzetta Ufficiale n. 23 del 29 gennaio 2020, \u00e8 stata fissata al 29 marzo 2020 la data del referendum confermativo popolare, che vedr\u00e0 coinvolti anche i cittadini italiani residenti all\u2019estero.<\/p>\n<p style=\"text-align: justify;\">Si ricorda che il <strong>VOTO \u00e8 un DIRITTO<\/strong> tutelato dalla Costituzione Italiana e che, in base alla Legge 27 dicembre 2001, n.459, i cittadini italiani residenti all\u2019estero, <strong>iscritti nelle liste elettorali, possono VOTARE PER POSTA<\/strong>. A tal fine, si raccomanda quindi di controllare e regolarizzare la propria situazione anagrafica e di indirizzo presso il proprio consolato.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c8 POSSIBILE IN ALTERNATIVA, <span style=\"text-decoration: underline;\">PER GLI ELETTORI RESIDENTI ALL\u2019ESTERO ED ISCRITTI ALL\u2019AIRE<\/span>, SCEGLIERE DI VOTARE IN ITALIA PRESSO IL PROPRIO COMUNE DI ISCRIZIONE ELETTORALE, comunicando<\/strong> per iscritto la propria scelta (<strong><a href=\"resource\/doc\/2020\/01\/modulo_di_opzione_referendum_2020.pdf\">cliccare qui per scaricare il modello OPZIONE<\/a><\/strong>) al Consolato entro il 10\u00b0 giorno successivo alla indizione delle votazioni. Gli elettori che scelgono di votare in Italia in occasione della prossima consultazione referendaria, riceveranno dai rispettivi Comuni italiani la cartolina-avviso per votare presso i seggi elettorali in Italia.<\/p>\n<p style=\"text-align: justify;\">La scelta (opzione) di votare in Italia vale solo per una consultazione referendaria.<\/p>\n<p style=\"text-align: justify;\">Si ribadisce che<strong> in ogni caso l\u2019opzione DEVE <span style=\"text-decoration: underline;\">PERVENIRE<\/span> all\u2019Ufficio consolare NON OLTRE I DIECI GIORNI SUCCESSIVI A QUELLO DELL\u2019INDIZIONE DELLE VOTAZIONI, OVVERO ENTRO IL GIORNO <span style=\"text-decoration: underline;\">8 FEBBRAIO 2020<\/span><\/strong>. Tale comunicazione pu\u00f2 essere scritta su carta semplice e &#8211; per essere valida &#8211; deve contenere nome, cognome, data, luogo di nascita, luogo di residenza e firma dell\u2019elettore, accompagnata da copia di un documento di identit\u00e0 del dichiarante.<\/p>\n<p style=\"text-align: justify;\">Per tale comunicazione si pu\u00f2 anche utilizzare l\u2019apposito modulo scaricabile dal sito web del Ministero degli Affari Esteri e della Cooperazione Internazionale (www.esteri.it) o da quello del proprio Ufficio consolare.<\/p>\n<p style=\"text-align: justify;\">Come prescritto dalla normativa vigente, <span style=\"text-decoration: underline;\">sar\u00e0 cura degli elettori verificare che la comunicazione di opzione spedita per posta sia stata ricevuta in tempo utile dal proprio Ufficio consolare<\/span>.<\/p>\n<p style=\"text-align: justify;\">La scelta di votare in Italia pu\u00f2 essere successivamente <strong>REVOCATA<\/strong> con una comunicazione scritta da inviare o consegnare all\u2019Ufficio consolare con le stesse modalit\u00e0 ed <span style=\"text-decoration: underline;\">entro gli stessi termini previsti per l\u2019esercizio dell\u2019opzione<\/span>.<\/p>\n<p style=\"text-align: justify;\">Se si sceglie di rientrare in Italia per votare, la Legge <strong>NON<\/strong> prevede alcun tipo di <strong>rimborso<\/strong> per le spese di viaggio sostenute, ma solo agevolazioni tariffarie all\u2019interno del territorio italiano. Solo gli elettori residenti in Paesi dove non vi sono le condizioni per votare per corrispondenza (Legge 459\/2001, art. 20, comma 1-bis) hanno diritto al rimborso del 75 per cento del costo del biglietto di viaggio, in classe economica.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019UFFICIO CONSOLARE \u00c8 A DISPOSIZIONE PER OGNI ULTERIORE CHIARIMENTO<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"resource\/doc\/2020\/01\/modulo_di_opzione_referendum_2020.pdf\">Modulo di presentazione dell&#8217;opzione<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Il formulario potr\u00e0 essere inviato per e-mail alle seguenti caselle:\u00a0<\/p>\n<p style=\"text-align: justify;\"><a href=\"mailto:elezioni.gerusalemme@esteri.it\">elezioni.gerusalemme@esteri.it<\/a><\/p>\n<p style=\"text-align: justify;\"><a><\/a>e, per conoscenza a <a href=\"mailto:elettorale.gerusalemme@esteri.it\">consolare.gerusalemme@esteri.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"VOTO PER CORRISPONDENZA DEI CITTADINI ITALIANI RESIDENTI ALL\u2019ESTERO E OPZIONE DI VOTO IN ITALIA L\u2019Ufficio centrale per il referendum della Corte di Cassazione, con ordinanza depositata in data 23 gennaio 2020, ha dichiarato che la richiesta di referendum sul testo di legge costituzionale recante \u201cmodifica degli articoli 56, 57 e 59 della Costituzione in materia [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1381","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":0,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1381\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}