{"id":1319,"date":"2020-05-19T19:06:27","date_gmt":"2020-05-19T16:06:27","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2020\/05\/il-console-generale-fedele-incontra\/"},"modified":"2020-05-19T19:06:27","modified_gmt":"2020-05-19T16:06:27","slug":"il-console-generale-fedele-incontra","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2020\/05\/il-console-generale-fedele-incontra\/","title":{"rendered":"Il Console Generale Fedele incontra la Ministra per gli Affari Femminili, Amal Hamad, e il Ministro per gli Affari Sociali, Ahmad Majdalani"},"content":{"rendered":"<p>Ramallah, 19 maggio 2020<\/p>\n<p>Il Console Generale Fedele incontra la Ministra per gli Affari Femminili, Amal Hamad, e il Ministro per gli Affari Sociali, Ahmad Majdalani, per discutere di progetti a sostegno delle fasce pi\u00f9 vulnerabili della popolazione palestinese, duramente colpite dalla pandemia in corso e dalle sue conseguenze economiche.<\/p>\n","protected":false},"excerpt":{"rendered":"Ramallah, 19 maggio 2020 Il Console Generale Fedele incontra la Ministra per gli Affari Femminili, Amal Hamad, e il Ministro per gli Affari Sociali, Ahmad Majdalani, per discutere di progetti a sostegno delle fasce pi\u00f9 vulnerabili della popolazione palestinese, duramente colpite dalla pandemia in corso e dalle sue conseguenze economiche.","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1319","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1319"}],"version-history":[{"count":0,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1319\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1319"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}