{"id":1212,"date":"2021-02-25T12:24:34","date_gmt":"2021-02-25T10:24:34","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2021\/02\/proroga-di-validita-delle-patenti\/"},"modified":"2021-02-25T12:24:34","modified_gmt":"2021-02-25T10:24:34","slug":"proroga-di-validita-delle-patenti","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2021\/02\/proroga-di-validita-delle-patenti\/","title":{"rendered":"Proroga di validit\u00e0 delle patenti di guida italiane"},"content":{"rendered":"<p style=\"text-align: justify;\">Si comunica che il D.L. n.18\/2020, nel quadro delle misure precauzionali adottate a seguito della pandemia, ha adottato una serie di provvedimenti in relazione alla validit\u00e0 per l\u2019anno 2021 delle patenti di guida. In particolare:<\/p>\n<ul style=\"list-style-type: square;\">\n<li style=\"text-align: justify;\">in quanto titoli abilitativi alla guida: la validit\u00e0 delle patenti di guida rilasciate in Italia con scadenza compresa tra il 31 gennaio 2020 ed il 30 aprile 2021 \u00e8 stata prorogata fino al 29 luglio 2021;<\/li>\n<li style=\"text-align: justify;\">in quanto documenti di riconoscimento e per le finalit\u00e0 proprie di tali documenti: la validit\u00e0 delle patenti di guida rilasciate in Italia tra il 31 gennaio 2020 ed il 29 aprile \u00e8 stata prorogata fino al 30 aprile 2021.<\/li>\n<\/ul>\n<p>Si rende noto altres\u00ec che su tutto il territorio dell\u2019Unione Europea, Italia inclusa, la validit\u00e0 delle patenti di guida rilasciate da un altro Paese dell\u2019UE con scadenza ricompresa tra il 1\u00b0 febbraio 2020 ed il 31 agosto 2020 \u00e8 prorogata di sette mesi decorrenti dalla data di scadenza annotata sul documento stesso, con la sola esclusione dei Paesi che hanno espressamente prescelto di non applicare tale proroga Per informazioni di dettaglio si rinvia alla circolare del Ministero dei Trasporti n. 2143 del 21 gennaio 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"Si comunica che il D.L. n.18\/2020, nel quadro delle misure precauzionali adottate a seguito della pandemia, ha adottato una serie di provvedimenti in relazione alla validit\u00e0 per l\u2019anno 2021 delle patenti di guida. In particolare: in quanto titoli abilitativi alla guida: la validit\u00e0 delle patenti di guida rilasciate in Italia con scadenza compresa tra il [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1212","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":0,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}