{"id":1057,"date":"2022-08-02T10:26:19","date_gmt":"2022-08-02T07:26:19","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2022\/08\/elezioni-politiche-2022-elettori\/"},"modified":"2022-08-02T10:26:19","modified_gmt":"2022-08-02T07:26:19","slug":"elezioni-politiche-2022-elettori","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2022\/08\/elezioni-politiche-2022-elettori\/","title":{"rendered":"Elezioni Politiche 2022. Elettori temporaneamente all&#8217;estero"},"content":{"rendered":"<p>Gli elettori italiani che per motivi di lavoro, studio o cure mediche si trovano temporaneamente all\u2019estero per un periodo di almeno tre mesi nel quale ricade la data di svolgimento delle prossime elezioni politiche del 25 settembre 2022, nonch\u00e9 i familiari con loro conviventi, potranno esercitare il diritto di voto per corrispondenza (art. 4-bis, comma 1, legge 27 dicembre 2001, n. 459), ricevendo il plico elettorale contenente le schede per il voto all\u2019indirizzo di temporanea dimora all\u2019estero.<\/p>\n<p>Per esercitare il proprio diritto di voto per corrispondenza, tali elettori dovranno far pervenire <span style=\"text-decoration: underline;\"><strong>AL COMUNE<\/strong><\/span> d\u2019iscrizione nelle liste elettorali <strong>un\u2019apposita opzione entro mercoled\u00ec 24 agosto 2022.<\/strong><\/p>\n<p>L\u2019opzione (esercitabile tramite <a href=\"http:\/\/consgerusalemme.esteri.it\/consolato_gerusalemme\/resource\/doc\/2022\/08\/modelloopzionevoto_politiche_20220925_accessibile.pdf\" target=\"_blank\" rel=\"noopener\">il modulo allegato<\/a> o in carta libera) deve essere inviata <span style=\"text-decoration: underline;\"><strong>al Comune<\/strong><\/span> per posta, telefax, posta elettronica anche non certificata, oppure fatta pervenire a mano, sempre <span style=\"text-decoration: underline;\"><strong>al Comune<\/strong><\/span>, anche da persona diversa dall\u2019interessato.<\/p>\n<p>L\u2019opzione, obbligatoriamente corredata di copia di documento d\u2019identit\u00e0 valido dell\u2019elettore, deve in ogni caso contenere<span style=\"text-decoration: underline;\"><strong> l\u2019indirizzo postale estero completo cui va inviato il plico elettorale<\/strong><\/span>, l\u2019indicazione dell\u2019Ufficio consolare competente per territorio e una dichiarazione attestante il possesso dei requisiti per l\u2019ammissione al voto per corrispondenza (ovvero di trovarsi &#8211; per motivi di lavoro, studio o cure mediche &#8211; per un periodo di almeno tre mesi nel quale ricade la data di svolgimento delle consultazioni in un Paese estero in cui non si \u00e8 anagraficamente residenti, oppure che si \u00e8 familiare convivente di un cittadino che si trova nelle predette condizioni).<\/p>\n<p>L\u2019opzione va resa ai sensi degli articoli 46 e 47 del decreto del Presidente della Repubblica del 28 dicembre 2000, n. 445 (testo unico delle disposizioni legislative e regolamentari in materia di documentazione amministrativa), dichiarandosi consapevoli delle conseguenze penali in caso di dichiarazioni mendaci (art. 76 del citato DPR 445\/2000).<\/p>\n<p><strong>\u00c8 possibile la revoca<\/strong> dell\u2019opzione presentata secondo le modalit\u00e0 di cui sopra <strong>entro lo stesso termine (24 agosto 2022)<\/strong>. Si ricorda infine che l\u2019opzione \u00e8 valida esclusivamente per la consultazione elettorale cui si riferisce (ovvero, in questo caso, per le elezioni politiche del 25 settembre 2022).<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Gli elettori italiani che per motivi di lavoro, studio o cure mediche si trovano temporaneamente all\u2019estero per un periodo di almeno tre mesi nel quale ricade la data di svolgimento delle prossime elezioni politiche del 25 settembre 2022, nonch\u00e9 i familiari con loro conviventi, potranno esercitare il diritto di voto per corrispondenza (art. 4-bis, comma [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1057","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1057"}],"version-history":[{"count":0,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1057\/revisions"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1057"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}