{"id":1028,"date":"2022-11-25T11:20:07","date_gmt":"2022-11-25T09:20:07","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2022\/11\/25-novembre-giornata-internazionale\/"},"modified":"2023-12-04T18:43:24","modified_gmt":"2023-12-04T16:43:24","slug":"25-novembre-giornata-internazionale","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2022\/11\/25-novembre-giornata-internazionale\/","title":{"rendered":"25 novembre: Giornata Internazionale per l\u2019Eliminazione della Violenza contro le Donne"},"content":{"rendered":"<p>In occasione della Giornata internazionale per l\u2019eliminazione della violenza contro le donne, la Farnesina e la sua rete estera aderiscono alla campagna di sensibilizzazione \u201cUNITE! Activism to End Violence against Women &amp; Girls Orange the World: End Violence against Women Now!\u201d, promossa da UN Women, che nel 2022 \u00e8 focalizzata sul contributo fondamentale di movimenti, organizzazioni e attori della societ\u00e0 civile, incluse donne e ragazze attiviste, per aumentare il livello di consapevolezza nell\u2019opinione pubblica su questi temi. Il Ministero degli Affari Esteri e della Cooperazione Internazionale conferma l\u2019impegno ad accrescere gli sforzi verso la parit\u00e0 di genere e invita tutti a compiere nuovi importanti passi verso questo traguardo, che nessun Paese del mondo, ad oggi, pu\u00f2 dire di aver raggiunto.<\/p>\n<p>Donne, ragazze e bambine continuano ad essere, in molte aree del mondo, specialmente in situazioni di conflitto armato e di emergenze, vittime di discriminazioni, violenze, abusi e sfruttamento. La difficile condizione femminile ma anche, specularmente, il talento, il coraggio e il contributo che le donne possono dare alla costruzione di societ\u00e0 pi\u00f9 inclusive e resilienti \u00e8 tema centrale in alcune delle crisi pi\u00f9 gravi dell\u2019attualit\u00e0 internazionale, dall\u2019Afghanistan all\u2019Etiopia, dall\u2019Ucraina all\u2019Iran. Le conseguenze della pandemia da Covid-19, le guerre e le crisi protratte hanno aggravato le condizioni di vulnerabilit\u00e0 preesistenti e contribuito in modo sensibile all\u2019innalzamento dei casi di violenza domestica e degli abusi. I dati delle Nazioni Unite ci indicano che, ancora oggi, una donna su tre ha subito abusi e violenza, fisica o psicologica, nell\u2019arco della vita. Nel 2021, una donna su dieci \u00e8 stata vittima di violenza domestica.<br \/>\nDinanzi a questi dati allarmanti, l\u2019Italia torna a esprimere la pi\u00f9 ferma condanna contro ogni forma di discriminazione e violenza contro le donne, fenomeno inaccettabile e grave impedimento al raggiungimento della parit\u00e0 di genere, all\u2019effettivo godimento dei diritti e alla piena realizzazione personale.<\/p>\n<p>La lotta contro ogni forma di discriminazione, violenza e abusi contro donne e ragazze \u00e8 un impegno prioritario dell\u2019azione di politica estera del nostro Paese, che la Farnesina porta avanti sia sul piano diplomatico-negoziale sia attraverso iniziative di emergenza e di cooperazione allo sviluppo. Ne sono testimonianza le numerose campagne internazionali, come quelle per l\u2019eradicazione delle mutilazioni genitali femminili (MGF) e dei matrimoni precoci e forzati, che da sempre vedono l\u2019Italia in prima linea.<\/p>\n<p>Gli obiettivi dell\u2019eliminazione di ogni forma di violenza sulle donne e dell\u2019empowerment femminile, pilastri centrali dell\u2019azione di politica estera e cooperazione italiane, figuravano tra le priorit\u00e0 dell\u2019ultimo mandato italiano in Consiglio Diritti Umani delle Nazioni Unite (2019-2021), della Presidenza italiana del G20 nel 2021 (con la prima Conferenza di alto livello dedicata all\u2019empowerment femminile ed un evento ad hoc dedicato alle donne afghane a margine dell\u2019Assemblea Generale dell\u2019ONU) e del semestre di Presidenza italiana del Comitato dei Ministri del Consiglio d\u2019Europa (novembre 2021-maggio 2022), nel cui ambito l\u2019Italia sostiene e promuove la \u201cConvenzione sulla prevenzione e la lotta alla violenza contro le donne e la violenza domestica\u201d (o \u201cConvenzione di Istanbul\u201d).<\/p>\n<p>I conflitti attualmente in corso in numerose aree del mondo dimostrano ancora una volta come, in situazioni di guerre ed emergenze, le donne e le ragazze siano particolarmente esposte al rischio di violenze e abusi. Di qui la necessit\u00e0 di continuare a rafforzare il nostro impegno, insieme a tutti gli attori della Comunit\u00e0 Internazionale, inclusa la societ\u00e0 civile, per eradicare per sempre questi atti inaccettabili.<\/p>\n<p>Con riguardo all\u2019organizzazione interna dei metodi di lavoro, la Farnesina continua a promuovere pari opportunit\u00e0 di genere, come evidenziato anche dall\u2019adozione, lo scorso anno, della Circolare n. 3\/2021, con cui il MAECI si adegua ai pi\u00f9 elevati standard di promozione della parit\u00e0 tra i sessi. Allo stesso modo, con l\u2019adozione il 18 gennaio scorso della Circolare n. 1\/2022 avente ad oggetto l\u2019aggiornamento dei metodi di lavoro e il benessere organizzativo, \u00e8 stata ribadita la necessit\u00e0 di valorizzare sempre, nel lavoro quotidiano, la concreta attuazione del principio costituzionale di uguaglianza, inteso sia come divieto di discriminazione, sia come promozione attiva di una parit\u00e0 effettiva.<\/p>\n<p>Approfondimento<br \/>\nLa tutela e la promozione dei diritti delle donne, dell&#8217;uguaglianza di genere e dell\u2019empowerment femminile, nonch\u00e9 la lotta contro ogni forma di discriminazione e violenza a danno di donne, ragazze e bambine sono priorit\u00e0 dell&#8217;azione internazionale dell&#8217;Italia, nei contesti multilaterali e regionali, nelle relazioni bilaterali con gli altri Stati, nelle Organizzazioni Internazionali e nell\u2019ambito dei programmi di Cooperazione allo Sviluppo, per la piena realizzazione dell\u2019obiettivo di sviluppo sostenibile SDG 5 dell\u2019Agenda 2030, del Piano d\u2019Azione dell\u2019UE sui Diritti Umani e la Democrazia 2020-2024 e della Strategia UE sulla parit\u00e0 di genere 2020-2025.<br \/>\nAl riguardo, nel dicembre 2020 sono state adottate le Linee guida sull\u2019uguaglianza di genere e l\u2019empowerment delle donne, ragazze e bambine (2020-2024), redatte dall\u2019AICS con il concorso della Direzione Generale per la Cooperazione allo Sviluppo (DGCS) del Ministero degli Affari Esteri e della Cooperazione Internazionale. Le nuove linee guida mirano a rafforzare l\u2019impegno della cooperazione italiana per l\u2019eliminazione delle discriminazioni legate al genere attraverso progetti di sviluppo e definiscono i settori prioritari di intervento.<\/p>\n<p>L\u2019impegno dell\u2019Italia per l\u2019empowerment femminile si esprime attraverso il forte sostegno alla protezione, all\u2019autonomia e al pieno sviluppo umano, sociale, economico e culturale di ogni donna. Ci\u00f2 si declina in specifiche iniziative che vanno dalla salute femminile, materno-infantile, sessuale e riproduttiva, alla lotta contro le mutilazioni genitali femminili e i matrimoni precoci, al sostegno a programmi in favore dell\u2019educazione delle bambine e delle donne e a progetti di sviluppo dell\u2019imprenditoria femminile.<br \/>\nL\u2019Italia ha aderito anche alla Raccomandazione dell\u2019OCSE-DAC del 12 luglio 2019 per porre termine allo sfruttamento, agli abusi e alle molestie sessuali nell\u2019aiuto allo sviluppo e nell\u2019assistenza umanitaria. In tale contesto, l\u2019Italia ha costantemente sostenuto le politiche di \u201ctolleranza zero\u201d e le iniziative intraprese per il rafforzamento dei meccanismi di prevenzione, segnalazione, denuncia e protezione delle vittime. Questi temi figuravano tra le priorit\u00e0 del nostro ultimo mandato in Consiglio Diritti Umani delle Nazioni Unite (2019-2021) e del semestre di Presidenza italiana del Comitato dei Ministri del Consiglio d\u2019Europa (novembre 2021-maggio 2022).<br \/>\nL\u2019Italia sostiene con forza le campagne internazionali per l&#8217;eliminazione delle pratiche dannose contro donne e ragazze, come le mutilazioni genitali femminili e i matrimoni precoci e forzati, promuovendo e partecipando attivamente ai negoziati sulle relative risoluzioni dell&#8217;Assemblea Generale (AG) e del Consiglio Diritti Umani, ed erogando annualmente contributi volontari a numerose agenzie delle Nazioni Unite, fortemente impegnate nella lotta per l&#8217;uguaglianza di genere e l&#8217;empowerment di donne, ragazze e bambine (quali UNWOMEN, UNFPA, UNICEF). Le stesse Agenzie, inoltre, beneficiano dei fondi della Cooperazione Italiana per la realizzazione di iniziative umanitarie nei principali contesti di crisi, come ad esempio l\u2019Afghanistan, dove a seguito degli eventi dell\u2019agosto 2021 sono stati finanziati interventi con un focus specifico sui bisogni delle donne e delle bambine.<\/p>\n<p>L\u2019Italia partecipa attivamente, tramite contributi della Cooperazione italiana allo sviluppo, ai programmi multilaterali dedicati all\u2019eliminazione delle mutilazioni genitali femminili e dei matrimoni precoci e forzati.<\/p>\n<p>L\u2019Italia sostiene attivamente iniziative internazionali per prevenire la violenza sessuale in situazioni di conflitto e di emergenza, come la \u201cCall to Action on Protection from Gender-based Violence in Emergencies\u201d.<br \/>\nIn ambito nazionale, il MAECI partecipa con un proprio Rappresentante all\u2019Osservatorio sul fenomeno della violenza nei confronti delle donne e sulla violenza domestica, nell\u2019ambito del \u201cPiano strategico nazionale sulla violenza maschile contro le donne 2021-2023\u201d adottato dal Ministero per le Pari Opportunit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"In occasione della Giornata internazionale per l\u2019eliminazione della violenza contro le donne, la Farnesina e la sua rete estera aderiscono alla campagna di sensibilizzazione \u201cUNITE! Activism to End Violence against Women &amp; Girls Orange the World: End Violence against Women Now!\u201d, promossa da UN Women, che nel 2022 \u00e8 focalizzata sul contributo fondamentale di movimenti, [&hellip;]","protected":false},"author":1,"featured_media":2292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1028"}],"version-history":[{"count":1,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1028\/revisions"}],"predecessor-version":[{"id":2293,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1028\/revisions\/2293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media\/2292"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1028"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}