{"id":1009,"date":"2023-07-28T10:02:12","date_gmt":"2023-07-28T07:02:12","guid":{"rendered":"https:\/\/consgerusalemme.esteri.it\/news\/dal_consolato\/2023\/07\/modifica-della-normativa-italiana\/"},"modified":"2023-11-28T17:50:31","modified_gmt":"2023-11-28T15:50:31","slug":"modifica-della-normativa-italiana","status":"publish","type":"post","link":"https:\/\/consgerusalemme.esteri.it\/it\/news\/dal_consolato\/2023\/07\/modifica-della-normativa-italiana\/","title":{"rendered":"Modifica della normativa italiana in materia di assenso al rilascio di passaporto\/\/carta di identit\u00e0 in presenza di figli minori"},"content":{"rendered":"<p>Si informano i connazionali, genitori di figli minori, che a partire dal 14 giugno 2023 non \u00e8 pi\u00f9 necessario presentare l\u2019atto di assenso dell\u2019altro genitore ai fini del rilascio del proprio\u00a0documento d\u2019identit\u00e0 (passaporto e carta di identit\u00e0 elettronica), ai sensi del Decreto Legge n. 69\/2023. Per il rilascio del proprio documento sar\u00e0 sufficiente che i genitori con prole minore autocertifichino di non essere sottoposto a inibitoria al rilascio del passaporto. Tale dichiarazione \u00e8 contenuta nel modulo di richiesta del passaporto e deve essere resa indipendentemente dalla nazionalit\u00e0 dell\u2019altro genitore e anche se si tratta di genitore non coniugato, separato o divorziato.<\/p>\n<p>Nello specifico il testo dell\u2019articolo 3-bis della Legge n. 1185\/1967 indica che, quando vi \u00e8 concreto e attuale pericolo che a causa del rilascio del documento il genitore richiedente possa sottrarsi all\u2019adempimento dei suoi obblighi verso i figli, sar\u00e0 possibile per l\u2019altro genitore richiedere una inibitoria al rilascio del documento.<\/p>\n<p>L\u2019istanza potr\u00e0 essere presentata presso il giudice competente presso il Tribunale ordinario in cui il minore ha la residenza abituale ovvero, se il minore \u00e8 residente all\u2019estero, il Tribunale nel cui circondario si trova il suo Comune di iscrizione A.I.R.E.<\/p>\n<p>Ai fini del rilascio dei documenti per i minori, invece, resta l\u2019obbligo dell\u2019assenso firmato da entrambi i genitori o da chi esercita la responsabilit\u00e0 genitoriale.<\/p>\n<p>Per ogni ulteriore dettaglio vi invitiamo a far riferimento alle nostre pagine web su <a href=\"..\/consolato_gerusalemme\/it\/informazioni_e_servizi\/servizi_consolari\/nuovopassaporto.html\">passaporti<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Si informano i connazionali, genitori di figli minori, che a partire dal 14 giugno 2023 non \u00e8 pi\u00f9 necessario presentare l\u2019atto di assenso dell\u2019altro genitore ai fini del rilascio del proprio\u00a0documento d\u2019identit\u00e0 (passaporto e carta di identit\u00e0 elettronica), ai sensi del Decreto Legge n. 69\/2023. Per il rilascio del proprio documento sar\u00e0 sufficiente che i [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1009","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1009"}],"version-history":[{"count":1,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1009\/revisions"}],"predecessor-version":[{"id":2241,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1009\/revisions\/2241"}],"wp:attachment":[{"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1009"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consgerusalemme.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}